{"id":394,"count":14,"description":"","link":"https:\/\/cosmeticalixone.com\/eu\/oliba-olioa\/","name":"OLIBA OLIOA","slug":"oliba-olioa","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":25,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>OLIBA OLIOA archivos - Lixon\u00e9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cosmeticalixone.com\/aceite-oliva\/\" \/>\n<meta property=\"og:locale\" content=\"eu_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OLIBA OLIOA archivos - Lixon\u00e9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cosmeticalixone.com\/aceite-oliva\/\" \/>\n<meta property=\"og:site_name\" content=\"Lixon\u00e9\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/cosmeticalixone.com\\\/aceite-oliva\\\/\",\"url\":\"https:\\\/\\\/cosmeticalixone.com\\\/aceite-oliva\\\/\",\"name\":\"OLIBA OLIOA archivos - Lixon\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cosmeticalixone.com\\\/aceite-oliva\\\/#breadcrumb\"},\"inLanguage\":\"eu-ES\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cosmeticalixone.com\\\/aceite-oliva\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cosmeticalixone.com\\\/eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ACEITE DE OLIVA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/\",\"name\":\"Lixon\u00e9\",\"description\":\"Laboratorios LIXON\u00c9, nace en 1986 para dar respuesta a las necesidades Dermatol\u00f3gicas, de Cosm\u00e9tica e Higiene Personal, a trav\u00e9s de la fabricaci\u00f3n de productos naturales con extractos vegetales.\",\"publisher\":{\"@id\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/#organization\",\"name\":\"LIXON\u00c9 - Cosm\u00e9tca Natural\",\"url\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cosmeticalixone.com\\\/wp-content\\\/uploads\\\/lixone-logo-peque\u00f1o.png\",\"contentUrl\":\"https:\\\/\\\/cosmeticalixone.com\\\/wp-content\\\/uploads\\\/lixone-logo-peque\u00f1o.png\",\"width\":160,\"height\":71,\"caption\":\"LIXON\u00c9 - Cosm\u00e9tca Natural\"},\"image\":{\"@id\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cosmeticalixone\",\"https:\\\/\\\/www.instagram.com\\\/cosmeticalixone\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OLIBA OLIOA archivos - Lixon\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cosmeticalixone.com\/aceite-oliva\/","og_locale":"eu_ES","og_type":"article","og_title":"OLIBA OLIOA archivos - Lixon\u00e9","og_url":"https:\/\/cosmeticalixone.com\/aceite-oliva\/","og_site_name":"Lixon\u00e9","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/cosmeticalixone.com\/aceite-oliva\/","url":"https:\/\/cosmeticalixone.com\/aceite-oliva\/","name":"OLIBA OLIOA archivos - Lixon\u00e9","isPartOf":{"@id":"https:\/\/cosmeticalixone.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/cosmeticalixone.com\/aceite-oliva\/#breadcrumb"},"inLanguage":"eu-ES"},{"@type":"BreadcrumbList","@id":"https:\/\/cosmeticalixone.com\/aceite-oliva\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cosmeticalixone.com\/eu\/"},{"@type":"ListItem","position":2,"name":"ACEITE DE OLIVA"}]},{"@type":"WebSite","@id":"https:\/\/cosmeticalixone.com\/en\/#website","url":"https:\/\/cosmeticalixone.com\/en\/","name":"Lixon\u00e9","description":"Laboratorios LIXON\u00c9, nace en 1986 para dar respuesta a las necesidades Dermatol\u00f3gicas, de Cosm\u00e9tica e Higiene Personal, a trav\u00e9s de la fabricaci\u00f3n de productos naturales con extractos vegetales.","publisher":{"@id":"https:\/\/cosmeticalixone.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cosmeticalixone.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu-ES"},{"@type":"Organization","@id":"https:\/\/cosmeticalixone.com\/en\/#organization","name":"LIXON\u00c9 - Cosm\u00e9tca Natural","url":"https:\/\/cosmeticalixone.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/cosmeticalixone.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/cosmeticalixone.com\/wp-content\/uploads\/lixone-logo-peque\u00f1o.png","contentUrl":"https:\/\/cosmeticalixone.com\/wp-content\/uploads\/lixone-logo-peque\u00f1o.png","width":160,"height":71,"caption":"LIXON\u00c9 - Cosm\u00e9tca Natural"},"image":{"@id":"https:\/\/cosmeticalixone.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cosmeticalixone","https:\/\/www.instagram.com\/cosmeticalixone\/"]}]}},"_links":{"self":[{"href":"https:\/\/cosmeticalixone.com\/eu\/wp-json\/wp\/v2\/product_cat\/394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cosmeticalixone.com\/eu\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/cosmeticalixone.com\/eu\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/cosmeticalixone.com\/eu\/wp-json\/wp\/v2\/product?product_cat=394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}