{"id":25297,"date":"2014-12-09T12:02:18","date_gmt":"2014-12-09T11:02:18","guid":{"rendered":"http:\/\/aplicaciones.debamatika.com\/lixone\/?post_type=product&#038;p=25297"},"modified":"2021-12-02T22:38:29","modified_gmt":"2021-12-02T21:38:29","slug":"oliba-oliozko-oin-krema-150-ml","status":"publish","type":"product","link":"https:\/\/cosmeticalixone.com\/eu\/erosi\/oin-krema\/oliba-oliozko-oin-krema-150-ml\/","title":{"rendered":"Oliba-Oliozko OIN-KREMA 150 ml"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p><span>Ez koipetsua. <\/span><\/p>\n<p><span>Xurgatze errazekoa. <\/span><span>Animalietatik eratorritako osagairik gabea <\/span><\/p>\n<p><span>Landare-jatorrizko olio eta estraktua.<\/span><\/p>\n","protected":false},"featured_media":30995,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[349,367,394],"product_tag":[],"class_list":["post-25297","product","type-product","status-publish","has-post-thumbnail","product_cat-gorputz-zaintzea","product_cat-oin-krema","product_cat-oliba-olioa","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CREMA de PIES de Aceite de Oliva 150 ml<\/title>\n<meta name=\"description\" content=\"El aceite de oliva virgen extra posee propiedades hidratantes, suavizantes. Con extracto cosm\u00e9tico vegetal, ofrece una sensaci\u00f3n de frescor y bienestar.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cosmeticalixone.com\/eu\/oliba-oliozko-oin-krema-150-ml\/\" \/>\n<meta property=\"og:locale\" content=\"eu_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CREMA de PIES de Aceite de Oliva 150 ml\" \/>\n<meta property=\"og:description\" content=\"El aceite de oliva virgen extra posee propiedades hidratantes, suavizantes. Con extracto cosm\u00e9tico vegetal, ofrece una sensaci\u00f3n de frescor y bienestar.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cosmeticalixone.com\/eu\/oliba-oliozko-oin-krema-150-ml\/\" \/>\n<meta property=\"og:site_name\" content=\"Lixon\u00e9\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cosmeticalixone\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-02T21:38:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cosmeticalixone.com\/wp-content\/uploads\/crema-pies-aceite-oliva.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"450\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cosmeticalixone.com\\\/eu\\\/oliba-oliozko-oin-krema-150-ml\\\/\",\"url\":\"https:\\\/\\\/cosmeticalixone.com\\\/eu\\\/oliba-oliozko-oin-krema-150-ml\\\/\",\"name\":\"CREMA de PIES de Aceite de Oliva 150 ml\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cosmeticalixone.com\\\/eu\\\/oliba-oliozko-oin-krema-150-ml\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cosmeticalixone.com\\\/eu\\\/oliba-oliozko-oin-krema-150-ml\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cosmeticalixone.com\\\/wp-content\\\/uploads\\\/crema-pies-aceite-oliva-2x1.jpg\",\"datePublished\":\"2014-12-09T11:02:18+00:00\",\"dateModified\":\"2021-12-02T21:38:29+00:00\",\"description\":\"El aceite de oliva virgen extra posee propiedades hidratantes, suavizantes. Con extracto cosm\u00e9tico vegetal, ofrece una sensaci\u00f3n de frescor y bienestar.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cosmeticalixone.com\\\/eu\\\/oliba-oliozko-oin-krema-150-ml\\\/#breadcrumb\"},\"inLanguage\":\"eu-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cosmeticalixone.com\\\/eu\\\/oliba-oliozko-oin-krema-150-ml\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/cosmeticalixone.com\\\/eu\\\/oliba-oliozko-oin-krema-150-ml\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cosmeticalixone.com\\\/wp-content\\\/uploads\\\/crema-pies-aceite-oliva-2x1.jpg\",\"contentUrl\":\"https:\\\/\\\/cosmeticalixone.com\\\/wp-content\\\/uploads\\\/crema-pies-aceite-oliva-2x1.jpg\",\"width\":450,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cosmeticalixone.com\\\/eu\\\/oliba-oliozko-oin-krema-150-ml\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cosmeticalixone.com\\\/eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Denda\",\"item\":\"https:\\\/\\\/cosmeticalixone.com\\\/eu\\\/online-denda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Oliba-Oliozko OIN-KREMA 150 ml\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/\",\"name\":\"Lixon\u00e9\",\"description\":\"Laboratorios LIXON\u00c9, nace en 1986 para dar respuesta a las necesidades Dermatol\u00f3gicas, de Cosm\u00e9tica e Higiene Personal, a trav\u00e9s de la fabricaci\u00f3n de productos naturales con extractos vegetales.\",\"publisher\":{\"@id\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/#organization\",\"name\":\"LIXON\u00c9 - Cosm\u00e9tca Natural\",\"url\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cosmeticalixone.com\\\/wp-content\\\/uploads\\\/lixone-logo-peque\u00f1o.png\",\"contentUrl\":\"https:\\\/\\\/cosmeticalixone.com\\\/wp-content\\\/uploads\\\/lixone-logo-peque\u00f1o.png\",\"width\":160,\"height\":71,\"caption\":\"LIXON\u00c9 - Cosm\u00e9tca Natural\"},\"image\":{\"@id\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cosmeticalixone\",\"https:\\\/\\\/www.instagram.com\\\/cosmeticalixone\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CREMA de PIES de Aceite de Oliva 150 ml","description":"El aceite de oliva virgen extra posee propiedades hidratantes, suavizantes. Con extracto cosm\u00e9tico vegetal, ofrece una sensaci\u00f3n de frescor y bienestar.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cosmeticalixone.com\/eu\/oliba-oliozko-oin-krema-150-ml\/","og_locale":"eu_ES","og_type":"article","og_title":"CREMA de PIES de Aceite de Oliva 150 ml","og_description":"El aceite de oliva virgen extra posee propiedades hidratantes, suavizantes. Con extracto cosm\u00e9tico vegetal, ofrece una sensaci\u00f3n de frescor y bienestar.","og_url":"https:\/\/cosmeticalixone.com\/eu\/oliba-oliozko-oin-krema-150-ml\/","og_site_name":"Lixon\u00e9","article_publisher":"https:\/\/www.facebook.com\/cosmeticalixone","article_modified_time":"2021-12-02T21:38:29+00:00","og_image":[{"width":450,"height":450,"url":"https:\/\/cosmeticalixone.com\/wp-content\/uploads\/crema-pies-aceite-oliva.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cosmeticalixone.com\/eu\/oliba-oliozko-oin-krema-150-ml\/","url":"https:\/\/cosmeticalixone.com\/eu\/oliba-oliozko-oin-krema-150-ml\/","name":"CREMA de PIES de Aceite de Oliva 150 ml","isPartOf":{"@id":"https:\/\/cosmeticalixone.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cosmeticalixone.com\/eu\/oliba-oliozko-oin-krema-150-ml\/#primaryimage"},"image":{"@id":"https:\/\/cosmeticalixone.com\/eu\/oliba-oliozko-oin-krema-150-ml\/#primaryimage"},"thumbnailUrl":"https:\/\/cosmeticalixone.com\/wp-content\/uploads\/crema-pies-aceite-oliva-2x1.jpg","datePublished":"2014-12-09T11:02:18+00:00","dateModified":"2021-12-02T21:38:29+00:00","description":"El aceite de oliva virgen extra posee propiedades hidratantes, suavizantes. Con extracto cosm\u00e9tico vegetal, ofrece una sensaci\u00f3n de frescor y bienestar.","breadcrumb":{"@id":"https:\/\/cosmeticalixone.com\/eu\/oliba-oliozko-oin-krema-150-ml\/#breadcrumb"},"inLanguage":"eu-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cosmeticalixone.com\/eu\/oliba-oliozko-oin-krema-150-ml\/"]}]},{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/cosmeticalixone.com\/eu\/oliba-oliozko-oin-krema-150-ml\/#primaryimage","url":"https:\/\/cosmeticalixone.com\/wp-content\/uploads\/crema-pies-aceite-oliva-2x1.jpg","contentUrl":"https:\/\/cosmeticalixone.com\/wp-content\/uploads\/crema-pies-aceite-oliva-2x1.jpg","width":450,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/cosmeticalixone.com\/eu\/oliba-oliozko-oin-krema-150-ml\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cosmeticalixone.com\/eu\/"},{"@type":"ListItem","position":2,"name":"Denda","item":"https:\/\/cosmeticalixone.com\/eu\/online-denda\/"},{"@type":"ListItem","position":3,"name":"Oliba-Oliozko OIN-KREMA 150 ml"}]},{"@type":"WebSite","@id":"https:\/\/cosmeticalixone.com\/en\/#website","url":"https:\/\/cosmeticalixone.com\/en\/","name":"Lixon\u00e9","description":"Laboratorios LIXON\u00c9, nace en 1986 para dar respuesta a las necesidades Dermatol\u00f3gicas, de Cosm\u00e9tica e Higiene Personal, a trav\u00e9s de la fabricaci\u00f3n de productos naturales con extractos vegetales.","publisher":{"@id":"https:\/\/cosmeticalixone.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cosmeticalixone.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu-ES"},{"@type":"Organization","@id":"https:\/\/cosmeticalixone.com\/en\/#organization","name":"LIXON\u00c9 - Cosm\u00e9tca Natural","url":"https:\/\/cosmeticalixone.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/cosmeticalixone.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/cosmeticalixone.com\/wp-content\/uploads\/lixone-logo-peque\u00f1o.png","contentUrl":"https:\/\/cosmeticalixone.com\/wp-content\/uploads\/lixone-logo-peque\u00f1o.png","width":160,"height":71,"caption":"LIXON\u00c9 - Cosm\u00e9tca Natural"},"image":{"@id":"https:\/\/cosmeticalixone.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cosmeticalixone","https:\/\/www.instagram.com\/cosmeticalixone\/"]}]}},"_links":{"self":[{"href":"https:\/\/cosmeticalixone.com\/eu\/wp-json\/wp\/v2\/product\/25297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cosmeticalixone.com\/eu\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/cosmeticalixone.com\/eu\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/cosmeticalixone.com\/eu\/wp-json\/wp\/v2\/comments?post=25297"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cosmeticalixone.com\/eu\/wp-json\/wp\/v2\/media\/30995"}],"wp:attachment":[{"href":"https:\/\/cosmeticalixone.com\/eu\/wp-json\/wp\/v2\/media?parent=25297"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/cosmeticalixone.com\/eu\/wp-json\/wp\/v2\/product_brand?post=25297"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/cosmeticalixone.com\/eu\/wp-json\/wp\/v2\/product_cat?post=25297"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/cosmeticalixone.com\/eu\/wp-json\/wp\/v2\/product_tag?post=25297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}