{"id":25040,"date":"2014-12-07T23:42:29","date_gmt":"2014-12-07T22:42:29","guid":{"rendered":"http:\/\/aplicaciones.debamatika.com\/lixone\/?post_type=product&#038;p=25040"},"modified":"2021-12-02T22:38:16","modified_gmt":"2021-12-02T21:38:16","slug":"natural-glycerin-soap","status":"publish","type":"product","link":"https:\/\/cosmeticalixone.com\/en\/buy\/soaps\/natural-glycerin-soap\/","title":{"rendered":"Natural Glycerin SOAP"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Pack 3 x 125 g.<\/p>\n<p>All skin types.<\/p>\n<p>Without preservatives.<\/p>\n<p>Sparkling.<\/p>\n<p>For daily use.<\/p>\n<p>Vegetable glycerin.<\/p>\n","protected":false},"featured_media":32391,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[315,321],"product_tag":[413,460],"class_list":["post-25040","product","type-product","status-publish","has-post-thumbnail","product_cat-hygiene","product_cat-soaps","product_tag-glycerin","product_tag-soap","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>JABON de Glicerina Natural<\/title>\n<meta name=\"description\" content=\"Jab\u00f3n con alto contenido en glicerina de origen vegetal, mantiene el equilibrio de la piel gracias a su alto poder hidratante. Para manos, cara y cuerpo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cosmeticalixone.com\/en\/natural-glycerin-soap\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"JABON de Glicerina Natural\" \/>\n<meta property=\"og:description\" content=\"Jab\u00f3n con alto contenido en glicerina de origen vegetal, mantiene el equilibrio de la piel gracias a su alto poder hidratante. Para manos, cara y cuerpo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cosmeticalixone.com\/en\/natural-glycerin-soap\/\" \/>\n<meta property=\"og:site_name\" content=\"Lixon\u00e9\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cosmeticalixone\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-02T21:38:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cosmeticalixone.com\/wp-content\/uploads\/jabon-glicerina-natural.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"450\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/natural-glycerin-soap\\\/\",\"url\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/natural-glycerin-soap\\\/\",\"name\":\"JABON de Glicerina Natural\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/natural-glycerin-soap\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/natural-glycerin-soap\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cosmeticalixone.com\\\/wp-content\\\/uploads\\\/jabon-glicerina-natural.jpg\",\"datePublished\":\"2014-12-07T22:42:29+00:00\",\"dateModified\":\"2021-12-02T21:38:16+00:00\",\"description\":\"Jab\u00f3n con alto contenido en glicerina de origen vegetal, mantiene el equilibrio de la piel gracias a su alto poder hidratante. Para manos, cara y cuerpo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/natural-glycerin-soap\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/natural-glycerin-soap\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/natural-glycerin-soap\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cosmeticalixone.com\\\/wp-content\\\/uploads\\\/jabon-glicerina-natural.jpg\",\"contentUrl\":\"https:\\\/\\\/cosmeticalixone.com\\\/wp-content\\\/uploads\\\/jabon-glicerina-natural.jpg\",\"width\":450,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/natural-glycerin-soap\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Store\",\"item\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/online-store\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Natural Glycerin SOAP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/\",\"name\":\"Lixon\u00e9\",\"description\":\"Laboratorios LIXON\u00c9, nace en 1986 para dar respuesta a las necesidades Dermatol\u00f3gicas, de Cosm\u00e9tica e Higiene Personal, a trav\u00e9s de la fabricaci\u00f3n de productos naturales con extractos vegetales.\",\"publisher\":{\"@id\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/#organization\",\"name\":\"LIXON\u00c9 - Cosm\u00e9tca Natural\",\"url\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cosmeticalixone.com\\\/wp-content\\\/uploads\\\/lixone-logo-peque\u00f1o.png\",\"contentUrl\":\"https:\\\/\\\/cosmeticalixone.com\\\/wp-content\\\/uploads\\\/lixone-logo-peque\u00f1o.png\",\"width\":160,\"height\":71,\"caption\":\"LIXON\u00c9 - Cosm\u00e9tca Natural\"},\"image\":{\"@id\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cosmeticalixone\",\"https:\\\/\\\/www.instagram.com\\\/cosmeticalixone\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"JABON de Glicerina Natural","description":"Jab\u00f3n con alto contenido en glicerina de origen vegetal, mantiene el equilibrio de la piel gracias a su alto poder hidratante. Para manos, cara y cuerpo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cosmeticalixone.com\/en\/natural-glycerin-soap\/","og_locale":"en_US","og_type":"article","og_title":"JABON de Glicerina Natural","og_description":"Jab\u00f3n con alto contenido en glicerina de origen vegetal, mantiene el equilibrio de la piel gracias a su alto poder hidratante. Para manos, cara y cuerpo","og_url":"https:\/\/cosmeticalixone.com\/en\/natural-glycerin-soap\/","og_site_name":"Lixon\u00e9","article_publisher":"https:\/\/www.facebook.com\/cosmeticalixone","article_modified_time":"2021-12-02T21:38:16+00:00","og_image":[{"width":450,"height":450,"url":"https:\/\/cosmeticalixone.com\/wp-content\/uploads\/jabon-glicerina-natural.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cosmeticalixone.com\/en\/natural-glycerin-soap\/","url":"https:\/\/cosmeticalixone.com\/en\/natural-glycerin-soap\/","name":"JABON de Glicerina Natural","isPartOf":{"@id":"https:\/\/cosmeticalixone.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cosmeticalixone.com\/en\/natural-glycerin-soap\/#primaryimage"},"image":{"@id":"https:\/\/cosmeticalixone.com\/en\/natural-glycerin-soap\/#primaryimage"},"thumbnailUrl":"https:\/\/cosmeticalixone.com\/wp-content\/uploads\/jabon-glicerina-natural.jpg","datePublished":"2014-12-07T22:42:29+00:00","dateModified":"2021-12-02T21:38:16+00:00","description":"Jab\u00f3n con alto contenido en glicerina de origen vegetal, mantiene el equilibrio de la piel gracias a su alto poder hidratante. Para manos, cara y cuerpo","breadcrumb":{"@id":"https:\/\/cosmeticalixone.com\/en\/natural-glycerin-soap\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cosmeticalixone.com\/en\/natural-glycerin-soap\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cosmeticalixone.com\/en\/natural-glycerin-soap\/#primaryimage","url":"https:\/\/cosmeticalixone.com\/wp-content\/uploads\/jabon-glicerina-natural.jpg","contentUrl":"https:\/\/cosmeticalixone.com\/wp-content\/uploads\/jabon-glicerina-natural.jpg","width":450,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/cosmeticalixone.com\/en\/natural-glycerin-soap\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cosmeticalixone.com\/en\/"},{"@type":"ListItem","position":2,"name":"Store","item":"https:\/\/cosmeticalixone.com\/en\/online-store\/"},{"@type":"ListItem","position":3,"name":"Natural Glycerin SOAP"}]},{"@type":"WebSite","@id":"https:\/\/cosmeticalixone.com\/en\/#website","url":"https:\/\/cosmeticalixone.com\/en\/","name":"Lixon\u00e9","description":"Laboratorios LIXON\u00c9, nace en 1986 para dar respuesta a las necesidades Dermatol\u00f3gicas, de Cosm\u00e9tica e Higiene Personal, a trav\u00e9s de la fabricaci\u00f3n de productos naturales con extractos vegetales.","publisher":{"@id":"https:\/\/cosmeticalixone.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cosmeticalixone.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/cosmeticalixone.com\/en\/#organization","name":"LIXON\u00c9 - Cosm\u00e9tca Natural","url":"https:\/\/cosmeticalixone.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cosmeticalixone.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/cosmeticalixone.com\/wp-content\/uploads\/lixone-logo-peque\u00f1o.png","contentUrl":"https:\/\/cosmeticalixone.com\/wp-content\/uploads\/lixone-logo-peque\u00f1o.png","width":160,"height":71,"caption":"LIXON\u00c9 - Cosm\u00e9tca Natural"},"image":{"@id":"https:\/\/cosmeticalixone.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cosmeticalixone","https:\/\/www.instagram.com\/cosmeticalixone\/"]}]}},"_links":{"self":[{"href":"https:\/\/cosmeticalixone.com\/en\/wp-json\/wp\/v2\/product\/25040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cosmeticalixone.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/cosmeticalixone.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/cosmeticalixone.com\/en\/wp-json\/wp\/v2\/comments?post=25040"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cosmeticalixone.com\/en\/wp-json\/wp\/v2\/media\/32391"}],"wp:attachment":[{"href":"https:\/\/cosmeticalixone.com\/en\/wp-json\/wp\/v2\/media?parent=25040"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/cosmeticalixone.com\/en\/wp-json\/wp\/v2\/product_brand?post=25040"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/cosmeticalixone.com\/en\/wp-json\/wp\/v2\/product_cat?post=25040"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/cosmeticalixone.com\/en\/wp-json\/wp\/v2\/product_tag?post=25040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}