{"id":24970,"date":"2014-12-07T23:10:08","date_gmt":"2014-12-07T22:10:08","guid":{"rendered":"http:\/\/aplicaciones.debamatika.com\/lixone\/?post_type=product&#038;p=24970"},"modified":"2021-12-02T22:38:32","modified_gmt":"2021-12-02T21:38:32","slug":"olive-oil-bath-shower-gel-250-ml","status":"publish","type":"product","link":"https:\/\/cosmeticalixone.com\/en\/buy\/bath-and-shower-gel\/olive-oil-bath-shower-gel-250-ml\/","title":{"rendered":"Olive Oil BATH &#038; SHOWER GEL 250 ml."},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Dry skin.<\/p>\n<p>Vegetable glycerin and oil extracts.<\/p>\n","protected":false},"featured_media":36463,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[318,315,393],"product_tag":[412],"class_list":["post-24970","product","type-product","status-publish","has-post-thumbnail","product_cat-bath-and-shower-gel","product_cat-hygiene","product_cat-olive-oil","product_tag-bath-and-shower","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GEL de BA\u00d1O y DUCHA de Aceite de Oliva 250 ml.<\/title>\n<meta name=\"description\" content=\"Elaborado con Aceites y Glicerina de origen vegetal. El Aceite de Oliva posee propiedades hidratantes, suavizantes y emolientes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cosmeticalixone.com\/en\/olive-oil-bath-shower-gel-250-ml\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GEL de BA\u00d1O y DUCHA de Aceite de Oliva 250 ml.\" \/>\n<meta property=\"og:description\" content=\"Elaborado con Aceites y Glicerina de origen vegetal. El Aceite de Oliva posee propiedades hidratantes, suavizantes y emolientes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cosmeticalixone.com\/en\/olive-oil-bath-shower-gel-250-ml\/\" \/>\n<meta property=\"og:site_name\" content=\"Lixon\u00e9\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cosmeticalixone\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-02T21:38:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cosmeticalixone.com\/wp-content\/uploads\/gel-ducha-aceite-oliva-250ml-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"450\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/olive-oil-bath-shower-gel-250-ml\\\/\",\"url\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/olive-oil-bath-shower-gel-250-ml\\\/\",\"name\":\"GEL de BA\u00d1O y DUCHA de Aceite de Oliva 250 ml.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/olive-oil-bath-shower-gel-250-ml\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/olive-oil-bath-shower-gel-250-ml\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cosmeticalixone.com\\\/wp-content\\\/uploads\\\/gel-aceite-oliva-250ml.jpg\",\"datePublished\":\"2014-12-07T22:10:08+00:00\",\"dateModified\":\"2021-12-02T21:38:32+00:00\",\"description\":\"Elaborado con Aceites y Glicerina de origen vegetal. El Aceite de Oliva posee propiedades hidratantes, suavizantes y emolientes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/olive-oil-bath-shower-gel-250-ml\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/olive-oil-bath-shower-gel-250-ml\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/olive-oil-bath-shower-gel-250-ml\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cosmeticalixone.com\\\/wp-content\\\/uploads\\\/gel-aceite-oliva-250ml.jpg\",\"contentUrl\":\"https:\\\/\\\/cosmeticalixone.com\\\/wp-content\\\/uploads\\\/gel-aceite-oliva-250ml.jpg\",\"width\":450,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/olive-oil-bath-shower-gel-250-ml\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Store\",\"item\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/online-store\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Olive Oil BATH &#038; SHOWER GEL 250 ml.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/\",\"name\":\"Lixon\u00e9\",\"description\":\"Laboratorios LIXON\u00c9, nace en 1986 para dar respuesta a las necesidades Dermatol\u00f3gicas, de Cosm\u00e9tica e Higiene Personal, a trav\u00e9s de la fabricaci\u00f3n de productos naturales con extractos vegetales.\",\"publisher\":{\"@id\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/#organization\",\"name\":\"LIXON\u00c9 - Cosm\u00e9tca Natural\",\"url\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cosmeticalixone.com\\\/wp-content\\\/uploads\\\/lixone-logo-peque\u00f1o.png\",\"contentUrl\":\"https:\\\/\\\/cosmeticalixone.com\\\/wp-content\\\/uploads\\\/lixone-logo-peque\u00f1o.png\",\"width\":160,\"height\":71,\"caption\":\"LIXON\u00c9 - Cosm\u00e9tca Natural\"},\"image\":{\"@id\":\"https:\\\/\\\/cosmeticalixone.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cosmeticalixone\",\"https:\\\/\\\/www.instagram.com\\\/cosmeticalixone\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GEL de BA\u00d1O y DUCHA de Aceite de Oliva 250 ml.","description":"Elaborado con Aceites y Glicerina de origen vegetal. El Aceite de Oliva posee propiedades hidratantes, suavizantes y emolientes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cosmeticalixone.com\/en\/olive-oil-bath-shower-gel-250-ml\/","og_locale":"en_US","og_type":"article","og_title":"GEL de BA\u00d1O y DUCHA de Aceite de Oliva 250 ml.","og_description":"Elaborado con Aceites y Glicerina de origen vegetal. El Aceite de Oliva posee propiedades hidratantes, suavizantes y emolientes.","og_url":"https:\/\/cosmeticalixone.com\/en\/olive-oil-bath-shower-gel-250-ml\/","og_site_name":"Lixon\u00e9","article_publisher":"https:\/\/www.facebook.com\/cosmeticalixone","article_modified_time":"2021-12-02T21:38:32+00:00","og_image":[{"width":450,"height":450,"url":"https:\/\/cosmeticalixone.com\/wp-content\/uploads\/gel-ducha-aceite-oliva-250ml-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cosmeticalixone.com\/en\/olive-oil-bath-shower-gel-250-ml\/","url":"https:\/\/cosmeticalixone.com\/en\/olive-oil-bath-shower-gel-250-ml\/","name":"GEL de BA\u00d1O y DUCHA de Aceite de Oliva 250 ml.","isPartOf":{"@id":"https:\/\/cosmeticalixone.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cosmeticalixone.com\/en\/olive-oil-bath-shower-gel-250-ml\/#primaryimage"},"image":{"@id":"https:\/\/cosmeticalixone.com\/en\/olive-oil-bath-shower-gel-250-ml\/#primaryimage"},"thumbnailUrl":"https:\/\/cosmeticalixone.com\/wp-content\/uploads\/gel-aceite-oliva-250ml.jpg","datePublished":"2014-12-07T22:10:08+00:00","dateModified":"2021-12-02T21:38:32+00:00","description":"Elaborado con Aceites y Glicerina de origen vegetal. El Aceite de Oliva posee propiedades hidratantes, suavizantes y emolientes.","breadcrumb":{"@id":"https:\/\/cosmeticalixone.com\/en\/olive-oil-bath-shower-gel-250-ml\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cosmeticalixone.com\/en\/olive-oil-bath-shower-gel-250-ml\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cosmeticalixone.com\/en\/olive-oil-bath-shower-gel-250-ml\/#primaryimage","url":"https:\/\/cosmeticalixone.com\/wp-content\/uploads\/gel-aceite-oliva-250ml.jpg","contentUrl":"https:\/\/cosmeticalixone.com\/wp-content\/uploads\/gel-aceite-oliva-250ml.jpg","width":450,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/cosmeticalixone.com\/en\/olive-oil-bath-shower-gel-250-ml\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cosmeticalixone.com\/en\/"},{"@type":"ListItem","position":2,"name":"Store","item":"https:\/\/cosmeticalixone.com\/en\/online-store\/"},{"@type":"ListItem","position":3,"name":"Olive Oil BATH &#038; SHOWER GEL 250 ml."}]},{"@type":"WebSite","@id":"https:\/\/cosmeticalixone.com\/en\/#website","url":"https:\/\/cosmeticalixone.com\/en\/","name":"Lixon\u00e9","description":"Laboratorios LIXON\u00c9, nace en 1986 para dar respuesta a las necesidades Dermatol\u00f3gicas, de Cosm\u00e9tica e Higiene Personal, a trav\u00e9s de la fabricaci\u00f3n de productos naturales con extractos vegetales.","publisher":{"@id":"https:\/\/cosmeticalixone.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cosmeticalixone.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/cosmeticalixone.com\/en\/#organization","name":"LIXON\u00c9 - Cosm\u00e9tca Natural","url":"https:\/\/cosmeticalixone.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cosmeticalixone.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/cosmeticalixone.com\/wp-content\/uploads\/lixone-logo-peque\u00f1o.png","contentUrl":"https:\/\/cosmeticalixone.com\/wp-content\/uploads\/lixone-logo-peque\u00f1o.png","width":160,"height":71,"caption":"LIXON\u00c9 - Cosm\u00e9tca Natural"},"image":{"@id":"https:\/\/cosmeticalixone.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cosmeticalixone","https:\/\/www.instagram.com\/cosmeticalixone\/"]}]}},"_links":{"self":[{"href":"https:\/\/cosmeticalixone.com\/en\/wp-json\/wp\/v2\/product\/24970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cosmeticalixone.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/cosmeticalixone.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/cosmeticalixone.com\/en\/wp-json\/wp\/v2\/comments?post=24970"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cosmeticalixone.com\/en\/wp-json\/wp\/v2\/media\/36463"}],"wp:attachment":[{"href":"https:\/\/cosmeticalixone.com\/en\/wp-json\/wp\/v2\/media?parent=24970"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/cosmeticalixone.com\/en\/wp-json\/wp\/v2\/product_brand?post=24970"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/cosmeticalixone.com\/en\/wp-json\/wp\/v2\/product_cat?post=24970"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/cosmeticalixone.com\/en\/wp-json\/wp\/v2\/product_tag?post=24970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}